{"id":1667,"date":"2016-05-12T16:40:41","date_gmt":"2016-05-12T20:40:41","guid":{"rendered":"http:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1.jpg"},"modified":"2016-05-12T16:40:41","modified_gmt":"2016-05-12T20:40:41","slug":"a-liens1-768x575","status":"inherit","type":"attachment","link":"https:\/\/lacmercier.ca\/en\/a-liens1-768x575\/","title":{"rendered":"A-liens1-768&#215;575"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-1667","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1-300x225.jpg 300w, https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1.jpg 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":768,"height":575,"file":"2016\/05\/A-liens1-768x575-1.jpg","sizes":{"thumbnail":{"file":"A-liens1-768x575-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1-150x150.jpg"},"medium":{"file":"A-liens1-768x575-1-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1-300x225.jpg"},"medium_large":{"file":"A-liens1-768x575-1-768x575.jpg","width":768,"height":575,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1-768x575.jpg"},"full":{"file":"A-liens1-768x575-1.jpg","width":768,"height":575,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/A-liens1-768x575-1.jpg","filename":"A-liens1-768x575-1.jpg","filesize":null,"_links":{"self":[{"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/media\/1667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/comments?post=1667"}]}}