{"id":1625,"date":"2016-05-12T16:40:16","date_gmt":"2016-05-12T20:40:16","guid":{"rendered":"http:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil.jpg"},"modified":"2020-03-26T15:13:21","modified_gmt":"2020-03-26T19:13:21","slug":"accueil","status":"inherit","type":"attachment","link":"https:\/\/lacmercier.ca\/en\/accueil\/","title":{"rendered":"Accueil"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-1625","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil-300x94.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil-300x94.jpg 300w, https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil-768x241.jpg 768w, https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil-1024x322.jpg 1024w, https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil.jpg 1328w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1328,"height":417,"file":"2016\/05\/Accueil.jpg","sizes":{"thumbnail":{"file":"Accueil-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil-150x150.jpg"},"medium":{"file":"Accueil-300x94.jpg","width":300,"height":94,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil-300x94.jpg"},"medium_large":{"file":"Accueil-768x241.jpg","width":768,"height":241,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil-768x241.jpg"},"large":{"file":"Accueil-1024x322.jpg","width":1024,"height":322,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil-1024x322.jpg"},"full":{"file":"Accueil.jpg","width":1328,"height":417,"mime_type":"image\/jpeg","source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/lacmercier.ca\/wp-content\/uploads\/2016\/05\/Accueil.jpg","_links":{"self":[{"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/media\/1625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacmercier.ca\/en\/wp-json\/wp\/v2\/comments?post=1625"}]}}